{"id":8701,"date":"2008-07-07T15:00:06","date_gmt":"2008-07-07T14:00:06","guid":{"rendered":"http:\/\/rockpixx.com\/wordpress\/?p=8701"},"modified":"2013-02-22T12:48:43","modified_gmt":"2013-02-22T11:48:43","slug":"ey-alda-mach-mal-n-bild-von-mir","status":"publish","type":"post","link":"http:\/\/www.rockpixx.com\/wordpress\/ey-alda-mach-mal-n-bild-von-mir\/","title":{"rendered":"\u201eEy Alda, mach&#8216; mal &#8217;n Bild von mir!\u201c"},"content":{"rendered":"<p><strong>\u2026 oder warum ich Partyknipser eigentlich nicht leiden kann&#8230;<\/strong><\/p>\n<p>Nicht, dass mich hier jemand falsch versteht: Ich pflege nicht mehr in Diskotheken oder \u00e4hnliche Etablissement zu gehen \u2013 nachdem ich Anfang der Achtziger Jahre des letzten Jahrhunderts zu Studentenzeiten lange Zeit als Discjockey gearbeitet habe (ich bin tats\u00e4chlich schon so alt!), habe ich f\u00fcr meine Restlebenszeit vermutlich gen\u00fcgend \u201eDiskothekencharme\u201c inhaliert, um jetzt noch dort aufzuschlagen\u2026<\/p>\n<p>Seitdem digitale Kameras erschwinglich geworden sind, seitdem es Foren und \u00e4hnliche Communities im www gibt, wo solche Bilder gezeigt werden k\u00f6nnen und seitdem einige Zeitgenossen festgestellt haben, dass eine DSLR plus Aufsteckblitz plus imposantem Bouncer m\u00e4chtig Eindruck machen k\u00f6nnen (und es vielleicht sogar noch ein Freigetr\u00e4nk f\u00fcr&#8217;s Knipsen gibt), seit dieser Zeit also hat auch eine Bewusstseins-Ver\u00e4nderung beim fotografierten Publikum eingesetzt.<\/p>\n<p>Deshalb jetzt auch die Erkl\u00e4rung f\u00fcr irritierte Leser, warum so ein Beitrag unter so einer Headline auf einer Konzertfotoseite steht. Stellen wir uns doch einmal die folgende Situation vor:<!--more--><\/p>\n<p>Die Band steht auf der B\u00fchne und gibt ihr Bestes. Der Lichtmensch macht aus den vorhandenen M\u00f6glichkeiten ebenfalls das Beste und der Fotograf (in diesem Fall ich) versucht, die Stimmung so einzufangen, dass am Ende alle zufrieden sind \u2013 nachvollziehbar, oder?<\/p>\n<p>Und jetzt kommt&#8217;s: W\u00e4hrend ich also durch den Sucher irgendein Bandmitglied verfolge, um einen \u201eguten Schuss\u201c zu erhaschen, werde ich im besten Fall an der Schulter angetippt (im \u00fcbelsten Fall kr\u00e4ftig in den R\u00fccken gepatscht, herumgedreht oder es wird mir unvermittelt ins Ohr gebr\u00fcllt):<\/p>\n<p>\u201eEy Alda, mach&#8216; &#8218;mal &#8217;n Bild<\/p>\n<ul>\n<li>[_] von mir,<\/li>\n<li>[_] mir und meiner Tusse,<\/li>\n<li>[_] mir und meinen Kumpels,<\/li>\n<li>[_] (egal)!\u201c<\/li>\n<\/ul>\n<p>Ja, muss das denn sein? Ich mache auf dem Gig auch nur meine Arbeit, die sich aber darauf beschr\u00e4nkt, Musiker (und ggf. noch Publikum als solches) abzulichten. Ich bin nicht der Fotod\u00f6del, der irgendwelche mit Bierbuddeln posierenden d\u00e4mlichen Grinsies knipst. Leider verstehen das nicht alle und wollen dann noch mit mir diskutieren, warum denn nicht und sie seien das doch so gewohnt aus der Disse.<\/p>\n<p>Das wiederum best\u00e4rkt mich dann wieder einmal in meiner Ansicht, dass ein Herr Pawlow heute nicht mehr mit Hunden, Fresschen und Gl\u00f6ckchen experimentieren w\u00fcrde. Vermutlich n\u00e4hme er heute eine Digitalkamera und ganz normales Diskothekenpublikum. Und irgendwie werde ich auch den Verdacht nicht los, dass die ungez\u00e4hlten Partyknipser an dieser Verhaltensweise mancher Konzertbesucher nicht ganz unschuldig sind\u2026<\/p>\n<p>Versteht jetzt jemand die obige \u00dcberschrift?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2026 oder warum ich Partyknipser eigentlich nicht leiden kann&#8230; Nicht, dass mich hier jemand falsch <a href=\"http:\/\/www.rockpixx.com\/wordpress\/ey-alda-mach-mal-n-bild-von-mir\/\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"\u201eEy Alda, mach' mal 'n Bild von mir!\u201c","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[277,19],"tags":[870,212],"class_list":["post-8701","post","type-post","status-publish","format-standard","hentry","category-277","category-backstage","tag-partyknipser","tag-publikum"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":22535,"url":"http:\/\/www.rockpixx.com\/wordpress\/motoerizer-2022\/","url_meta":{"origin":8701,"position":0},"title":"Mot\u00f6rizer, 22.04.2022, Kiel, R\u00e4ucherei","author":"A. Hahl","date":"23. April 2022","format":false,"excerpt":"846 Tage ist es her, seit dem letzten Konzert von \u201eMot\u00f6rizer\u201c welches ich in Hamburg in der Markthalle fotografiert habe. Leider ist es auch generell 846 Tage her, seitdem ich zum letzten Mal (mit der Kamera in den H\u00e4nden) \u00fcberhaupt vor einer Konzertb\u00fchne gestanden habe.","rel":"","context":"In &quot;Acts&quot;","block_context":{"text":"Acts","link":"http:\/\/www.rockpixx.com\/wordpress\/category\/acts\/"},"img":{"alt_text":"Mot\u00f6rizer, 22.04.2022, Kiel, R\u00e4ucherei | rockpixx.com","src":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2022\/04\/20220422-rp-109.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2022\/04\/20220422-rp-109.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2022\/04\/20220422-rp-109.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2022\/04\/20220422-rp-109.jpg?resize=700%2C400 2x"},"classes":[]},{"id":8694,"url":"http:\/\/www.rockpixx.com\/wordpress\/was-ich-bei-einem-gig-alles-so-dabei-habe\/","url_meta":{"origin":8701,"position":1},"title":"Was ich bei einem Gig alles so dabei habe\u2026","author":"admin","date":"25. Januar 2008","format":false,"excerpt":"Oft werde ich gefragt, womit ich denn so fotografiere und was f\u00fcr Konzertfotografie denn nun die \u201erichtige Ausr\u00fcstung\u201c sei. Und genauso oft gibt es in diversen Internet-Fotoforen dar\u00fcber erbitterte Diskussionen \u2013 am lautesten oft von denjenigen Deppen gef\u00fchrt, die noch nie ein brauchbares Bild vorzeigen konnten bzw. \u00fcber den Status\u2026","rel":"","context":"In &quot;2008&quot;","block_context":{"text":"2008","link":"http:\/\/www.rockpixx.com\/wordpress\/category\/backstage\/2008\/"},"img":{"alt_text":"20080125-akt","src":"https:\/\/i0.wp.com\/rockpixx.com\/wordpress\/wp-content\/uploads\/2008\/01\/20080125-akt.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":18327,"url":"http:\/\/www.rockpixx.com\/wordpress\/kellerkaos-22-06-2015-kieler-woche-netuse-buehne-kiel\/","url_meta":{"origin":8701,"position":2},"title":"KellerKaos, 22.06.2015, Kieler Woche, NetUSE-B\u00fchne, Kiel","author":"Anja","date":"23. Juni 2015","format":false,"excerpt":"Vorab: Es gibt Bands, die ich nicht kenne (das ist auch nicht verwunderlich) und auf die ich mich schon im Vorfeld freue \u2013 so geschehen bei \u201eKellerKaos\u201c. Meine Erwartungen sollten nicht entt\u00e4uscht werden\u2026 In Kiel herrschte durch diverse Unf\u00e4lle an strategisch wichtigen Stellen nicht Keller- sondern Verkehrschaos. Schon im Stau\u2026","rel":"","context":"In &quot;Acts&quot;","block_context":{"text":"Acts","link":"http:\/\/www.rockpixx.com\/wordpress\/category\/acts\/"},"img":{"alt_text":"KellerKaos, 22.06.2015, NetUSE-B\u00fchne, Kiel","src":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2015\/06\/20150622-01-014_kellerkaos_Artikel.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2015\/06\/20150622-01-014_kellerkaos_Artikel.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2015\/06\/20150622-01-014_kellerkaos_Artikel.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2015\/06\/20150622-01-014_kellerkaos_Artikel.jpg?resize=700%2C400 2x"},"classes":[]},{"id":16425,"url":"http:\/\/www.rockpixx.com\/wordpress\/woa-2014-ein-fazit-zum-25-jubilaeum\/","url_meta":{"origin":8701,"position":3},"title":"W:O:A 2014 \u2013 Ein Fazit zum 25. Jubil\u00e4um","author":"admin","date":"5. August 2014","format":false,"excerpt":"Das war jetzt also mein drittes W:O:A als Fotograf mit Pitpass in Folge.\u00a0\u00a0Zeit, mit ein paar Tagen Abstand ein pers\u00f6nliches Fazit zu den Arbeitsbedingungen zu ziehen. Mit diesem Hintergrund seien die folgenden Anmerkungen auch zu verstehen. Ich kann also nicht auf Erfahrungen zur\u00fcckgreifen, wie toll das alles zu den Zeiten\u2026","rel":"","context":"In &quot;2014&quot;","block_context":{"text":"2014","link":"http:\/\/www.rockpixx.com\/wordpress\/category\/backstage\/2014\/"},"img":{"alt_text":"Impressionen, 31.07.2014, Wacken Open Air, Wacken","src":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2014\/08\/20140731-00-019.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2014\/08\/20140731-00-019.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2014\/08\/20140731-00-019.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2014\/08\/20140731-00-019.jpg?resize=700%2C400 2x"},"classes":[]},{"id":1018,"url":"http:\/\/www.rockpixx.com\/wordpress\/canon-regelt-cps-neu\/","url_meta":{"origin":8701,"position":4},"title":"Canon regelt CPS neu","author":"admin","date":"7. April 2010","format":false,"excerpt":"Moin, so, nun ist's amtlich! Heute lag in der (Brief-) Post ein Schreiben von Canon, in dem die Neustrukturierung des CPS erkl\u00e4rt wurde. Dort konnte ich jetzt nachlesen, dass es zuk\u00fcnftig die Stufen \u201ePlatin\u201c, \u201eGold\u201c und \u201eSilber\u201c (plus einer \u201eVideostufe\u201c) geben wird. Die Einteilung in diese Stufen regelt das vorhandene\u2026","rel":"","context":"In &quot;2010&quot;","block_context":{"text":"2010","link":"http:\/\/www.rockpixx.com\/wordpress\/category\/backstage\/2010\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":967,"url":"http:\/\/www.rockpixx.com\/wordpress\/beobachtungen-zu-fotografierenden-zeitgenossen-auf-konzerten\/","url_meta":{"origin":8701,"position":5},"title":"Beobachtungen zu fotografierenden Zeitgenossen auf Konzerten","author":"admin","date":"22. November 2007","format":false,"excerpt":"Der Besuch eines Konzertes ist f\u00fcr wohl fast jeden Besucher ein tolles Erlebnis. Verst\u00e4ndlich, dass so etwas auch in Bild und\/oder Ton festgehalten werden soll. Nun muss aber unterschieden werden, wer da so alles Bilder macht \u2013 fangen wir doch 'mal mit einer groben Unterteilung an: 1. \u201eNormale\u201c Besucher \u2026\u2026","rel":"","context":"In &quot;2007&quot;","block_context":{"text":"2007","link":"http:\/\/www.rockpixx.com\/wordpress\/category\/backstage\/2007\/"},"img":{"alt_text":"Fotodeppen","src":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2007\/11\/20091010-0308.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2007\/11\/20091010-0308.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2007\/11\/20091010-0308.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.rockpixx.com\/wordpress\/wp-content\/uploads\/2007\/11\/20091010-0308.jpg?resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:09:07","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/posts\/8701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8701"}],"version-history":[{"count":0,"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/posts\/8701\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/categories?post=8701"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rockpixx.com\/wordpress\/wp-json\/wp\/v2\/tags?post=8701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}